{"id":1416,"date":"2018-07-03T12:08:05","date_gmt":"2018-07-03T10:08:05","guid":{"rendered":"https:\/\/romuloparraabogado.jcdigital.es\/?p=1416"},"modified":"2021-06-25T20:43:46","modified_gmt":"2021-06-25T18:43:46","slug":"ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos","status":"publish","type":"post","link":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos","title":{"rendered":"(Espa\u00f1ol) Ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/romuloparraabogado.com\/es\/wp-json\/wp\/v2\/posts\/1416\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espa\u00f1ol<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Espa\u00f1ol.<\/p>\n","protected":false},"author":1,"featured_media":1420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[13,299,298],"class_list":["post-1416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionalidad","tag-adquirir-nacionalidad-espanola","tag-espanol-de-origen","tag-ley-de-nietos"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Proposici\u00f3n de ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos. Estado de las discusiones en el Senado y en la C\u00e1mara de Diputados.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"R\u00f3mulo Parra\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Romulo Parra Spanish lawyer | Abogado de extranjer\u00eda, nacionalidad espa\u00f1ola, residencia espa\u00f1ola, emigrar a Espa\u00f1a, negocios Espa\u00f1a. Relocate to Spain, lawyer for foreigners wishing to move to or invest in Spain.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ley de nietos o de descendientes de espa\u00f1oles\" \/>\n\t\t<meta property=\"og:description\" content=\"Proposici\u00f3n de ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos. Estado de las discusiones en el Senado y en la C\u00e1mara de Diputados.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/romuloparraabogado.com\/wp-content\/uploads\/2018\/07\/Ley-de-nacionalidad-para-descendientes-de-espa\u00f1oles-o-ley-de-nietos.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/romuloparraabogado.com\/wp-content\/uploads\/2018\/07\/Ley-de-nacionalidad-para-descendientes-de-espa\u00f1oles-o-ley-de-nietos.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2175\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1223\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-07-03T10:08:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-06-25T18:43:46+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RomuloParraAbogado\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ley de nietos o de descendientes de espa\u00f1oles\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Proposici\u00f3n de ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos. Estado de las discusiones en el Senado y en la C\u00e1mara de Diputados.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/romuloparraabogado.com\/wp-content\/uploads\/2018\/07\/Ley-de-nacionalidad-para-descendientes-de-espa\u00f1oles-o-ley-de-nietos.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#article\",\"name\":\"Ley de nietos o de descendientes de espa\\u00f1oles\",\"headline\":\"(Espa\\u00f1ol) Ley de nacionalidad para descendientes de espa\\u00f1oles o ley de nietos\",\"author\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/author\\\/letrado#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/romuloparraabogado.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Ley-de-nacionalidad-para-descendientes-de-espa\\u00f1oles-o-ley-de-nietos.jpg\",\"width\":2175,\"height\":1223,\"caption\":\"Ley de nacionalidad para descendientes de espa\\u00f1oles o ley de nietos\"},\"datePublished\":\"2018-07-03T12:08:05+02:00\",\"dateModified\":\"2021-06-25T20:43:46+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#webpage\"},\"articleSection\":\"Nacionalidad, adquirir nacionalidad espa\\u00f1ola, espa\\u00f1ol de origen, Ley de Nietos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/category\\\/nacionalidad#listItem\",\"name\":\"Nacionalidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/category\\\/nacionalidad#listItem\",\"position\":2,\"name\":\"Nacionalidad\",\"item\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/category\\\/nacionalidad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#listItem\",\"name\":\"(Espa\\u00f1ol) Ley de nacionalidad para descendientes de espa\\u00f1oles o ley de nietos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#listItem\",\"position\":3,\"name\":\"(Espa\\u00f1ol) Ley de nacionalidad para descendientes de espa\\u00f1oles o ley de nietos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/category\\\/nacionalidad#listItem\",\"name\":\"Nacionalidad\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/#person\",\"name\":\"R\\u00f3mulo Parra\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7195477219bb8ca9629f2836494efa8945bd320f2090b7c6a09ac028bbd5d8e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"R\\u00f3mulo Parra\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/author\\\/letrado#author\",\"url\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/author\\\/letrado\",\"name\":\"R\\u00f3mulo Parra\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7195477219bb8ca9629f2836494efa8945bd320f2090b7c6a09ac028bbd5d8e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"R\\u00f3mulo Parra\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#webpage\",\"url\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos\",\"name\":\"Ley de nietos o de descendientes de espa\\u00f1oles\",\"description\":\"Proposici\\u00f3n de ley de nacionalidad para descendientes de espa\\u00f1oles o ley de nietos. Estado de las discusiones en el Senado y en la C\\u00e1mara de Diputados.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/author\\\/letrado#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/author\\\/letrado#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/romuloparraabogado.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Ley-de-nacionalidad-para-descendientes-de-espa\\u00f1oles-o-ley-de-nietos.jpg\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos\\\/#mainImage\",\"width\":2175,\"height\":1223,\"caption\":\"Ley de nacionalidad para descendientes de espa\\u00f1oles o ley de nietos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#mainImage\"},\"datePublished\":\"2018-07-03T12:08:05+02:00\",\"dateModified\":\"2021-06-25T20:43:46+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/\",\"name\":\"Romulo Parra Spanish lawyer\",\"alternateName\":\"R\\u00f3mulo Parra Abogado de Extranjer\\u00eda e Inmigraci\\u00f3n en Espa\\u00f1a\",\"description\":\"Abogado de extranjer\\u00eda, nacionalidad espa\\u00f1ola, residencia espa\\u00f1ola, emigrar a Espa\\u00f1a, negocios Espa\\u00f1a. Relocate to Spain, lawyer for foreigners wishing to move to or invest in Spain.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/romuloparraabogado.com\\\/en\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ley de nietos o de descendientes de espa\u00f1oles","description":"Proposici\u00f3n de ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos. Estado de las discusiones en el Senado y en la C\u00e1mara de Diputados.","canonical_url":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#article","name":"Ley de nietos o de descendientes de espa\u00f1oles","headline":"(Espa\u00f1ol) Ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos","author":{"@id":"https:\/\/romuloparraabogado.com\/en\/author\/letrado#author"},"publisher":{"@id":"https:\/\/romuloparraabogado.com\/en\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/romuloparraabogado.com\/wp-content\/uploads\/2018\/07\/Ley-de-nacionalidad-para-descendientes-de-espa\u00f1oles-o-ley-de-nietos.jpg","width":2175,"height":1223,"caption":"Ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos"},"datePublished":"2018-07-03T12:08:05+02:00","dateModified":"2021-06-25T20:43:46+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#webpage"},"isPartOf":{"@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#webpage"},"articleSection":"Nacionalidad, adquirir nacionalidad espa\u00f1ola, espa\u00f1ol de origen, Ley de Nietos"},{"@type":"BreadcrumbList","@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/romuloparraabogado.com\/en#listItem","position":1,"name":"Inicio","item":"https:\/\/romuloparraabogado.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/romuloparraabogado.com\/en\/category\/nacionalidad#listItem","name":"Nacionalidad"}},{"@type":"ListItem","@id":"https:\/\/romuloparraabogado.com\/en\/category\/nacionalidad#listItem","position":2,"name":"Nacionalidad","item":"https:\/\/romuloparraabogado.com\/en\/category\/nacionalidad","nextItem":{"@type":"ListItem","@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#listItem","name":"(Espa\u00f1ol) Ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/romuloparraabogado.com\/en#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#listItem","position":3,"name":"(Espa\u00f1ol) Ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos","previousItem":{"@type":"ListItem","@id":"https:\/\/romuloparraabogado.com\/en\/category\/nacionalidad#listItem","name":"Nacionalidad"}}]},{"@type":"Person","@id":"https:\/\/romuloparraabogado.com\/en\/#person","name":"R\u00f3mulo Parra","image":{"@type":"ImageObject","@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/e7195477219bb8ca9629f2836494efa8945bd320f2090b7c6a09ac028bbd5d8e?s=96&d=mm&r=g","width":96,"height":96,"caption":"R\u00f3mulo Parra"}},{"@type":"Person","@id":"https:\/\/romuloparraabogado.com\/en\/author\/letrado#author","url":"https:\/\/romuloparraabogado.com\/en\/author\/letrado","name":"R\u00f3mulo Parra","image":{"@type":"ImageObject","@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e7195477219bb8ca9629f2836494efa8945bd320f2090b7c6a09ac028bbd5d8e?s=96&d=mm&r=g","width":96,"height":96,"caption":"R\u00f3mulo Parra"}},{"@type":"WebPage","@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#webpage","url":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos","name":"Ley de nietos o de descendientes de espa\u00f1oles","description":"Proposici\u00f3n de ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos. Estado de las discusiones en el Senado y en la C\u00e1mara de Diputados.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/romuloparraabogado.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#breadcrumblist"},"author":{"@id":"https:\/\/romuloparraabogado.com\/en\/author\/letrado#author"},"creator":{"@id":"https:\/\/romuloparraabogado.com\/en\/author\/letrado#author"},"image":{"@type":"ImageObject","url":"https:\/\/romuloparraabogado.com\/wp-content\/uploads\/2018\/07\/Ley-de-nacionalidad-para-descendientes-de-espa\u00f1oles-o-ley-de-nietos.jpg","@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos\/#mainImage","width":2175,"height":1223,"caption":"Ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos"},"primaryImageOfPage":{"@id":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos#mainImage"},"datePublished":"2018-07-03T12:08:05+02:00","dateModified":"2021-06-25T20:43:46+02:00"},{"@type":"WebSite","@id":"https:\/\/romuloparraabogado.com\/en\/#website","url":"https:\/\/romuloparraabogado.com\/en\/","name":"Romulo Parra Spanish lawyer","alternateName":"R\u00f3mulo Parra Abogado de Extranjer\u00eda e Inmigraci\u00f3n en Espa\u00f1a","description":"Abogado de extranjer\u00eda, nacionalidad espa\u00f1ola, residencia espa\u00f1ola, emigrar a Espa\u00f1a, negocios Espa\u00f1a. Relocate to Spain, lawyer for foreigners wishing to move to or invest in Spain.","inLanguage":"en-US","publisher":{"@id":"https:\/\/romuloparraabogado.com\/en\/#person"}}]},"og:locale":"en_US","og:site_name":"Romulo Parra Spanish lawyer | Abogado de extranjer\u00eda, nacionalidad espa\u00f1ola, residencia espa\u00f1ola, emigrar a Espa\u00f1a, negocios Espa\u00f1a. Relocate to Spain, lawyer for foreigners wishing to move to or invest in Spain.","og:type":"article","og:title":"Ley de nietos o de descendientes de espa\u00f1oles","og:description":"Proposici\u00f3n de ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos. Estado de las discusiones en el Senado y en la C\u00e1mara de Diputados.","og:url":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos","og:image":"https:\/\/romuloparraabogado.com\/wp-content\/uploads\/2018\/07\/Ley-de-nacionalidad-para-descendientes-de-espa\u00f1oles-o-ley-de-nietos.jpg","og:image:secure_url":"https:\/\/romuloparraabogado.com\/wp-content\/uploads\/2018\/07\/Ley-de-nacionalidad-para-descendientes-de-espa\u00f1oles-o-ley-de-nietos.jpg","og:image:width":2175,"og:image:height":1223,"article:published_time":"2018-07-03T10:08:05+00:00","article:modified_time":"2021-06-25T18:43:46+00:00","article:publisher":"https:\/\/www.facebook.com\/RomuloParraAbogado","twitter:card":"summary","twitter:title":"Ley de nietos o de descendientes de espa\u00f1oles","twitter:description":"Proposici\u00f3n de ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos. Estado de las discusiones en el Senado y en la C\u00e1mara de Diputados.","twitter:image":"https:\/\/romuloparraabogado.com\/wp-content\/uploads\/2018\/07\/Ley-de-nacionalidad-para-descendientes-de-espa\u00f1oles-o-ley-de-nietos.jpg"},"aioseo_meta_data":{"post_id":"1416","title":"Ley de nietos o de descendientes de espa\u00f1oles","description":"Proposici\u00f3n de&nbsp;ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos. Estado de las discusiones en el Senado y en la C\u00e1mara de Diputados.","keywords":[],"keyphrases":{"focus":{"keyphrase":"ley de nietos","score":100,"analysis":{"keyphraseInTitle":{"title":"Frase clave objetivo en el t\u00edtulo SEO","description":"Frase clave objetivo encontrada en el t\u00edtulo SEO.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Frase clave objetivo en la meta descripci\u00f3n","description":"Frase clave objetivo encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInURL":{"title":"Frase clave objetivo en la URL","description":"Frase clave objetivo usada en la URL.","score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"title":"Frase clave objetivo en la introducci\u00f3n","description":"Su Frase clave objetivo aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"title":"Frase clave objetivo sus subt\u00edtulos","description":"Sus subt\u00edtulos H2 y H3 reflejan el tema de su texto. \u00a1Buen trabajo!","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave objetivo","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":3},"keyphraseInImageAlt":[]}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-09 22:08:37","updated":"2025-06-13 18:34:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/romuloparraabogado.com\/en\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/romuloparraabogado.com\/en\/category\/nacionalidad\" title=\"Nacionalidad\">Nacionalidad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t(Espa\u00f1ol) Ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/romuloparraabogado.com\/en"},{"label":"Nacionalidad","link":"https:\/\/romuloparraabogado.com\/en\/category\/nacionalidad"},{"label":"(Espa\u00f1ol) Ley de nacionalidad para descendientes de espa\u00f1oles o ley de nietos","link":"https:\/\/romuloparraabogado.com\/en\/ley-de-nacionalidad-para-descendientes-de-espanoles-o-ley-de-nietos"}],"_links":{"self":[{"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/posts\/1416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/comments?post=1416"}],"version-history":[{"count":8,"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/posts\/1416\/revisions"}],"predecessor-version":[{"id":3325,"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/posts\/1416\/revisions\/3325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/media\/1420"}],"wp:attachment":[{"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/media?parent=1416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/categories?post=1416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/romuloparraabogado.com\/en\/wp-json\/wp\/v2\/tags?post=1416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}